{"id":59614,"date":"2026-06-28T03:05:17","date_gmt":"2026-06-28T03:05:17","guid":{"rendered":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/groepslessen-onbeperkt-abonnement-maandelijks-opzegbaar\/"},"modified":"2026-07-10T07:44:45","modified_gmt":"2026-07-10T07:44:45","slug":"the-boxing-academy-groepslessen-onbeperkt-abonnement-maandelijks-opzegbaar","status":"publish","type":"sportschool_abo","link":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/vlaardingen\/vlaardingen-centrum\/the-boxing-academy-groepslessen-onbeperkt-abonnement-maandelijks-opzegbaar\/","title":{"rendered":"The Boxing Academy: Groepslessen Onbeperkt Abonnement (Maandelijks opzegbaar)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"template":"","stad":[],"wijk":[],"class_list":["post-59614","sportschool_abo","type-sportschool_abo","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo\/59614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo"}],"about":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/types\/sportschool_abo"}],"wp:attachment":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media?parent=59614"}],"wp:term":[{"taxonomy":"stad","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/stad?post=59614"},{"taxonomy":"wijk","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/wijk?post=59614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}