{"id":62438,"date":"2026-06-29T03:09:53","date_gmt":"2026-06-29T03:09:53","guid":{"rendered":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/onbeperkt-sportabonnement-1-maand\/"},"modified":"2026-07-10T07:46:05","modified_gmt":"2026-07-10T07:46:05","slug":"five21-haarlem-onbeperkt-sportabonnement-1-maand","status":"publish","type":"sportschool_abo","link":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/haarlem\/haarlem-waarder-en-veerpolder\/five21-haarlem-onbeperkt-sportabonnement-1-maand\/","title":{"rendered":"Five21 Haarlem: Onbeperkt Sportabonnement (1 maand)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":52000,"template":"","stad":[],"wijk":[],"class_list":["post-62438","sportschool_abo","type-sportschool_abo","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo\/62438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo"}],"about":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/types\/sportschool_abo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media\/52000"}],"wp:attachment":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media?parent=62438"}],"wp:term":[{"taxonomy":"stad","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/stad?post=62438"},{"taxonomy":"wijk","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/wijk?post=62438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}