{"id":68690,"date":"2026-07-02T10:41:07","date_gmt":"2026-07-02T10:41:07","guid":{"rendered":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/premium-scholieren-studenten-en-65\/"},"modified":"2026-07-10T07:48:45","modified_gmt":"2026-07-10T07:48:45","slug":"gymbokx-premium-scholieren-studenten-en-65","status":"publish","type":"sportschool_abo","link":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/helmond\/helmond-helmond-west\/gymbokx-premium-scholieren-studenten-en-65\/","title":{"rendered":"GymBokx: Premium (Scholieren\/Studenten en 65+)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":22386,"template":"","stad":[],"wijk":[],"class_list":["post-68690","sportschool_abo","type-sportschool_abo","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo\/68690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo"}],"about":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/types\/sportschool_abo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media\/22386"}],"wp:attachment":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media?parent=68690"}],"wp:term":[{"taxonomy":"stad","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/stad?post=68690"},{"taxonomy":"wijk","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/wijk?post=68690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}