{"id":68888,"date":"2026-07-02T18:48:39","date_gmt":"2026-07-02T18:48:39","guid":{"rendered":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/maandabonnement-onbeperkt-doorlopend\/"},"modified":"2026-07-10T07:48:50","modified_gmt":"2026-07-10T07:48:50","slug":"yoga-innerwork-haarlem-maandabonnement-onbeperkt-doorlopend","status":"publish","type":"sportschool_abo","link":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/haarlem\/haarlem-ter-kleef-en-te-zaanen\/yoga-innerwork-haarlem-maandabonnement-onbeperkt-doorlopend\/","title":{"rendered":"Yoga Innerwork Haarlem: Maandabonnement Onbeperkt (doorlopend)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":46233,"template":"","stad":[],"wijk":[],"class_list":["post-68888","sportschool_abo","type-sportschool_abo","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo\/68888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo"}],"about":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/types\/sportschool_abo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media\/46233"}],"wp:attachment":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media?parent=68888"}],"wp:term":[{"taxonomy":"stad","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/stad?post=68888"},{"taxonomy":"wijk","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/wijk?post=68888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}