{"id":71134,"date":"2026-07-04T22:12:49","date_gmt":"2026-07-04T22:12:49","guid":{"rendered":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/all-inclusive-3-maanden\/"},"modified":"2026-07-10T07:50:14","modified_gmt":"2026-07-10T07:50:14","slug":"brajjestrajje-neje-all-inclusive-3-maanden","status":"publish","type":"sportschool_abo","link":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/haarlem\/haarlem-westoever-noord-buitenspaarne\/brajjestrajje-neje-all-inclusive-3-maanden\/","title":{"rendered":"Brajjestrajje N\u00e9je: All inclusive 3 maanden"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"template":"","stad":[],"wijk":[],"class_list":["post-71134","sportschool_abo","type-sportschool_abo","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo\/71134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo"}],"about":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/types\/sportschool_abo"}],"wp:attachment":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media?parent=71134"}],"wp:term":[{"taxonomy":"stad","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/stad?post=71134"},{"taxonomy":"wijk","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/wijk?post=71134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}