{"id":71139,"date":"2026-07-04T22:12:50","date_gmt":"2026-07-04T22:12:50","guid":{"rendered":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/exclusive-jeugd-studenten-tot-21-jaar-12-maanden-fitness\/"},"modified":"2026-07-10T07:50:14","modified_gmt":"2026-07-10T07:50:14","slug":"brajjestrajje-neje-exclusive-jeugd-studenten-tot-21-jaar-12-maanden-fitness","status":"publish","type":"sportschool_abo","link":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/haarlem\/haarlem-westoever-noord-buitenspaarne\/brajjestrajje-neje-exclusive-jeugd-studenten-tot-21-jaar-12-maanden-fitness\/","title":{"rendered":"Brajjestrajje N\u00e9je: Exclusive Jeugd &amp; studenten tot 21 jaar 12 maanden fitness"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"template":"","stad":[],"wijk":[],"class_list":["post-71139","sportschool_abo","type-sportschool_abo","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo\/71139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo"}],"about":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/types\/sportschool_abo"}],"wp:attachment":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media?parent=71139"}],"wp:term":[{"taxonomy":"stad","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/stad?post=71139"},{"taxonomy":"wijk","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/wijk?post=71139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}