{"id":74451,"date":"2026-07-14T04:21:03","date_gmt":"2026-07-14T04:21:03","guid":{"rendered":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/fitness-centrum-olympia-senioren-all-in-60\/"},"modified":"2026-07-14T04:21:03","modified_gmt":"2026-07-14T04:21:03","slug":"fitness-centrum-olympia-senioren-all-in-60","status":"publish","type":"sportschool_abo","link":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/schiedam\/schiedam-groenoord-en-kethel\/fitness-centrum-olympia-senioren-all-in-60\/","title":{"rendered":"Fitness Centrum Olympia: Senioren all-in (60+)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":22257,"template":"","stad":[],"wijk":[],"class_list":["post-74451","sportschool_abo","type-sportschool_abo","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo\/74451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo"}],"about":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/types\/sportschool_abo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media\/22257"}],"wp:attachment":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media?parent=74451"}],"wp:term":[{"taxonomy":"stad","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/stad?post=74451"},{"taxonomy":"wijk","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/wijk?post=74451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}