{"id":93137,"date":"2026-08-19T04:00:22","date_gmt":"2026-08-19T04:00:22","guid":{"rendered":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/beweegr-lessen-van-30-minuten-3x-per-week\/"},"modified":"2026-08-19T04:00:22","modified_gmt":"2026-08-19T04:00:22","slug":"beweegr-lessen-van-30-minuten-3x-per-week","status":"publish","type":"sportschool_abo","link":"https:\/\/sportlist.nl\/sportscholen\/abonnementen\/tilburg\/tilburg-binnenstad\/beweegr-lessen-van-30-minuten-3x-per-week\/","title":{"rendered":"BeweegR: Lessen van 30 minuten - 3x per week"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":52196,"template":"","stad":[],"wijk":[],"class_list":["post-93137","sportschool_abo","type-sportschool_abo","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo\/93137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/sportschool_abo"}],"about":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/types\/sportschool_abo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media\/52196"}],"wp:attachment":[{"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/media?parent=93137"}],"wp:term":[{"taxonomy":"stad","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/stad?post=93137"},{"taxonomy":"wijk","embeddable":true,"href":"https:\/\/sportlist.nl\/wp-json\/wp\/v2\/wijk?post=93137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}